{"id":46,"date":"2024-10-16T21:52:06","date_gmt":"2024-10-16T19:52:06","guid":{"rendered":"https:\/\/kinderhilfe-ma-gi-ta.de\/?page_id=46"},"modified":"2024-10-16T21:54:23","modified_gmt":"2024-10-16T19:54:23","slug":"dokumente","status":"publish","type":"page","link":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/dokumente\/","title":{"rendered":"Dokumente"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Aufnahmeantrag<\/h2>\n\n\n\n<p>Mit dem folgenden Aufnahmeantrag k\u00f6nnen Sie mit einem Mindestbeitrag von 20,00 \u20ac Vereinsmitglied werden. Damit unterst\u00fctzen Sie einen unserer wichtigsten Einkommenszweige.<\/p>\n\n\n\n<p><a href=\"https:\/\/kinderhilfe-ma-gi-ta.de\/wp-content\/uploads\/2024\/10\/Aufnahmeantrag.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Aufnahmeantrag<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufnahmeantrag Mit dem folgenden Aufnahmeantrag k\u00f6nnen Sie mit einem Mindestbeitrag von 20,00 \u20ac Vereinsmitglied werden. Damit unterst\u00fctzen Sie einen unserer wichtigsten Einkommenszweige. Aufnahmeantrag<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-46","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/pages\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":2,"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/pages\/46\/revisions"}],"predecessor-version":[{"id":52,"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/pages\/46\/revisions\/52"}],"wp:attachment":[{"href":"https:\/\/kinderhilfe-ma-gi-ta.de\/index.php\/wp-json\/wp\/v2\/media?parent=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}